{"id":361754,"date":"2022-11-02T08:58:47","date_gmt":"2022-11-02T06:58:47","guid":{"rendered":"https:\/\/light24.ee\/toode\/uncategorized\/the-trimless-inground-range-led\/"},"modified":"2022-11-02T08:58:47","modified_gmt":"2022-11-02T06:58:47","slug":"the-trimless-inground-range-led","status":"publish","type":"product","link":"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/","title":{"rendered":"Onelight Trimless Inground Led 6W 3000K"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":109422,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[10968,11016,10752],"product_tag":[11551],"class_list":["post-361754","product","type-product","status-publish","has-post-thumbnail","product_cat-outdoor-lighting","product_cat-outdoor-recessed-lights","product_cat-outlet","product_tag-onelight","pa_ip-kaitseklass-23496","pa_materjal-aluminium","pa_materjal-glass","pa_ruumid-garden","pa_ruumid-outdoor-area","pa_ruumid-pathway","pa_tarneaeg-3-days","pa_varv-must","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Light24 \u2600 Lighting E-Shop | Solutions d&#039;\u00e9clairage professionnelles\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Onelight Trimless Inground Led 6W 3000K \u2600 Light24\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/light24.lv\/wp-content\/uploads\/2022\/11\/69060.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/light24.lv\/wp-content\/uploads\/2022\/11\/69060.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-11-02T06:58:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-11-02T06:58:47+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/light24.ee\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Onelight Trimless Inground Led 6W 3000K \u2600 Light24\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/light24.lv\/wp-content\/uploads\/2022\/11\/69060.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/toode\\\/outdoor-lighting\\\/outdoor-recessed-lights\\\/the-trimless-inground-range-led\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/light24.lv#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/light24.lv\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/e-shop\\\/#listItem\",\"name\":\"E-shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/e-shop\\\/#listItem\",\"position\":2,\"name\":\"E-shop\",\"item\":\"https:\\\/\\\/light24.lv\\\/en\\\/e-shop\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/product-category\\\/outdoor-lighting\\\/#listItem\",\"name\":\"Outdoor lighting\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/light24.lv#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/product-category\\\/outdoor-lighting\\\/#listItem\",\"position\":3,\"name\":\"Outdoor lighting\",\"item\":\"https:\\\/\\\/light24.lv\\\/en\\\/product-category\\\/outdoor-lighting\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/product-category\\\/outdoor-lighting\\\/outdoor-recessed-lights\\\/#listItem\",\"name\":\"Outdoor recessed lights\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/e-shop\\\/#listItem\",\"name\":\"E-shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/product-category\\\/outdoor-lighting\\\/outdoor-recessed-lights\\\/#listItem\",\"position\":4,\"name\":\"Outdoor recessed lights\",\"item\":\"https:\\\/\\\/light24.lv\\\/en\\\/product-category\\\/outdoor-lighting\\\/outdoor-recessed-lights\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/toode\\\/outdoor-lighting\\\/outdoor-recessed-lights\\\/the-trimless-inground-range-led\\\/#listItem\",\"name\":\"Onelight Trimless Inground Led 6W 3000K\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/product-category\\\/outdoor-lighting\\\/#listItem\",\"name\":\"Outdoor lighting\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/toode\\\/outdoor-lighting\\\/outdoor-recessed-lights\\\/the-trimless-inground-range-led\\\/#listItem\",\"position\":5,\"name\":\"Onelight Trimless Inground Led 6W 3000K\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/product-category\\\/outdoor-lighting\\\/outdoor-recessed-lights\\\/#listItem\",\"name\":\"Outdoor recessed lights\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/light24.lv\\\/#organization\",\"name\":\"Light24\",\"description\":\"Lighting E-Shop | Solutions d'\\u00e9clairage professionnelles\",\"url\":\"https:\\\/\\\/light24.lv\\\/\",\"email\":\"info@light24.ee\",\"telephone\":\"+3725184133\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/light24.ee\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Shape-2-3.svg\",\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/toode\\\/outdoor-lighting\\\/outdoor-recessed-lights\\\/the-trimless-inground-range-led\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/toode\\\/outdoor-lighting\\\/outdoor-recessed-lights\\\/the-trimless-inground-range-led\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/light24.ee\",\"https:\\\/\\\/www.instagram.com\\\/light24official\\\/\"],\"address\":{\"@id\":\"https:\\\/\\\/light24.lv\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"P\\u00e4rnu str 146\",\"postalCode\":\"11317\",\"addressLocality\":\"Tallinn\",\"addressCountry\":\"EE\"},\"vatID\":\"EE101408174\"},{\"@type\":\"Product\",\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/toode\\\/outdoor-lighting\\\/outdoor-recessed-lights\\\/the-trimless-inground-range-led\\\/#wooCommerceProduct\",\"name\":\"Onelight Trimless Inground Led 6W 3000K\",\"url\":\"https:\\\/\\\/light24.lv\\\/en\\\/toode\\\/outdoor-lighting\\\/outdoor-recessed-lights\\\/the-trimless-inground-range-led\\\/\",\"sku\":\"1L100285\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/light24.lv\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/69060.jpg\",\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/toode\\\/outdoor-lighting\\\/outdoor-recessed-lights\\\/the-trimless-inground-range-led\\\/#productImage\",\"width\":1000,\"height\":1000},\"offers\":{\"@type\":\"Offer\",\"url\":\"https:\\\/\\\/light24.lv\\\/en\\\/toode\\\/outdoor-lighting\\\/outdoor-recessed-lights\\\/the-trimless-inground-range-led\\\/#wooCommerceOffer\",\"price\":75,\"priceCurrency\":\"EUR\",\"category\":\"Outdoor lighting\",\"availability\":\"https:\\\/\\\/schema.org\\\/InStock\",\"priceSpecification\":{\"@type\":\"PriceSpecification\",\"price\":75,\"priceCurrency\":\"EUR\",\"valueAddedTaxIncluded\":true},\"seller\":{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/light24.lv\\\/#organization\"}}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/toode\\\/outdoor-lighting\\\/outdoor-recessed-lights\\\/the-trimless-inground-range-led\\\/#webpage\",\"url\":\"https:\\\/\\\/light24.lv\\\/en\\\/toode\\\/outdoor-lighting\\\/outdoor-recessed-lights\\\/the-trimless-inground-range-led\\\/\",\"name\":\"Onelight Trimless Inground Led 6W 3000K \\u2600 Light24\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/light24.lv\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/toode\\\/outdoor-lighting\\\/outdoor-recessed-lights\\\/the-trimless-inground-range-led\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/light24.lv\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/69060.jpg\",\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/toode\\\/outdoor-lighting\\\/outdoor-recessed-lights\\\/the-trimless-inground-range-led\\\/#mainImage\",\"width\":1000,\"height\":1000},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/light24.lv\\\/en\\\/toode\\\/outdoor-lighting\\\/outdoor-recessed-lights\\\/the-trimless-inground-range-led\\\/#mainImage\"},\"datePublished\":\"2022-11-02T08:58:47+02:00\",\"dateModified\":\"2022-11-02T08:58:47+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/light24.lv\\\/#website\",\"url\":\"https:\\\/\\\/light24.lv\\\/\",\"name\":\"Light24\",\"description\":\"Lighting E-Shop | Solutions d'\\u00e9clairage professionnelles\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/light24.lv\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Onelight Trimless Inground Led 6W 3000K \u2600 Light24<\/title>\n\n","aioseo_head_json":{"title":"Onelight Trimless Inground Led 6W 3000K \u2600 Light24","description":"","canonical_url":"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/light24.lv#listItem","position":1,"name":"Home","item":"https:\/\/light24.lv","nextItem":{"@type":"ListItem","@id":"https:\/\/light24.lv\/en\/e-shop\/#listItem","name":"E-shop"}},{"@type":"ListItem","@id":"https:\/\/light24.lv\/en\/e-shop\/#listItem","position":2,"name":"E-shop","item":"https:\/\/light24.lv\/en\/e-shop\/","nextItem":{"@type":"ListItem","@id":"https:\/\/light24.lv\/en\/product-category\/outdoor-lighting\/#listItem","name":"Outdoor lighting"},"previousItem":{"@type":"ListItem","@id":"https:\/\/light24.lv#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/light24.lv\/en\/product-category\/outdoor-lighting\/#listItem","position":3,"name":"Outdoor lighting","item":"https:\/\/light24.lv\/en\/product-category\/outdoor-lighting\/","nextItem":{"@type":"ListItem","@id":"https:\/\/light24.lv\/en\/product-category\/outdoor-lighting\/outdoor-recessed-lights\/#listItem","name":"Outdoor recessed lights"},"previousItem":{"@type":"ListItem","@id":"https:\/\/light24.lv\/en\/e-shop\/#listItem","name":"E-shop"}},{"@type":"ListItem","@id":"https:\/\/light24.lv\/en\/product-category\/outdoor-lighting\/outdoor-recessed-lights\/#listItem","position":4,"name":"Outdoor recessed lights","item":"https:\/\/light24.lv\/en\/product-category\/outdoor-lighting\/outdoor-recessed-lights\/","nextItem":{"@type":"ListItem","@id":"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/#listItem","name":"Onelight Trimless Inground Led 6W 3000K"},"previousItem":{"@type":"ListItem","@id":"https:\/\/light24.lv\/en\/product-category\/outdoor-lighting\/#listItem","name":"Outdoor lighting"}},{"@type":"ListItem","@id":"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/#listItem","position":5,"name":"Onelight Trimless Inground Led 6W 3000K","previousItem":{"@type":"ListItem","@id":"https:\/\/light24.lv\/en\/product-category\/outdoor-lighting\/outdoor-recessed-lights\/#listItem","name":"Outdoor recessed lights"}}]},{"@type":"Organization","@id":"https:\/\/light24.lv\/#organization","name":"Light24","description":"Lighting E-Shop | Solutions d'\u00e9clairage professionnelles","url":"https:\/\/light24.lv\/","email":"info@light24.ee","telephone":"+3725184133","logo":{"@type":"ImageObject","url":"https:\/\/light24.ee\/wp-content\/uploads\/2022\/03\/Shape-2-3.svg","@id":"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/#organizationLogo"},"image":{"@id":"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/light24.ee","https:\/\/www.instagram.com\/light24official\/"],"address":{"@id":"https:\/\/light24.lv\/#postaladdress","@type":"PostalAddress","streetAddress":"P\u00e4rnu str 146","postalCode":"11317","addressLocality":"Tallinn","addressCountry":"EE"},"vatID":"EE101408174"},{"@type":"Product","@id":"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/#wooCommerceProduct","name":"Onelight Trimless Inground Led 6W 3000K","url":"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/","sku":"1L100285","image":{"@type":"ImageObject","url":"https:\/\/light24.lv\/wp-content\/uploads\/2022\/11\/69060.jpg","@id":"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/#productImage","width":1000,"height":1000},"offers":{"@type":"Offer","url":"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/#wooCommerceOffer","price":75,"priceCurrency":"EUR","category":"Outdoor lighting","availability":"https:\/\/schema.org\/InStock","priceSpecification":{"@type":"PriceSpecification","price":75,"priceCurrency":"EUR","valueAddedTaxIncluded":true},"seller":{"@type":"Organization","@id":"https:\/\/light24.lv\/#organization"}}},{"@type":"WebPage","@id":"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/#webpage","url":"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/","name":"Onelight Trimless Inground Led 6W 3000K \u2600 Light24","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/light24.lv\/#website"},"breadcrumb":{"@id":"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/light24.lv\/wp-content\/uploads\/2022\/11\/69060.jpg","@id":"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/#mainImage","width":1000,"height":1000},"primaryImageOfPage":{"@id":"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/#mainImage"},"datePublished":"2022-11-02T08:58:47+02:00","dateModified":"2022-11-02T08:58:47+02:00"},{"@type":"WebSite","@id":"https:\/\/light24.lv\/#website","url":"https:\/\/light24.lv\/","name":"Light24","description":"Lighting E-Shop | Solutions d'\u00e9clairage professionnelles","inLanguage":"en-US","publisher":{"@id":"https:\/\/light24.lv\/#organization"}}]},"og:locale":"en_US","og:site_name":"Light24 \u2600 Lighting E-Shop | Solutions d'\u00e9clairage professionnelles","og:type":"article","og:title":"Onelight Trimless Inground Led 6W 3000K \u2600 Light24","og:url":"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/","og:image":"https:\/\/light24.lv\/wp-content\/uploads\/2022\/11\/69060.jpg","og:image:secure_url":"https:\/\/light24.lv\/wp-content\/uploads\/2022\/11\/69060.jpg","og:image:width":1000,"og:image:height":1000,"article:published_time":"2022-11-02T06:58:47+00:00","article:modified_time":"2022-11-02T06:58:47+00:00","article:publisher":"https:\/\/www.facebook.com\/light24.ee","twitter:card":"summary_large_image","twitter:title":"Onelight Trimless Inground Led 6W 3000K \u2600 Light24","twitter:image":"https:\/\/light24.lv\/wp-content\/uploads\/2022\/11\/69060.jpg"},"aioseo_meta_data":{"post_id":"361754","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-04-28 07:59:35","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2026-03-16 04:10:51","updated":"2026-04-28 07:59:35","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/light24.lv\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/light24.lv\/en\/e-shop\/\" title=\"E-shop\">E-shop<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/light24.lv\/en\/product-category\/outdoor-lighting\/\" title=\"Outdoor lighting\">Outdoor lighting<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/light24.lv\/en\/product-category\/outdoor-lighting\/outdoor-recessed-lights\/\" title=\"Outdoor recessed lights\">Outdoor recessed lights<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tOnelight Trimless Inground Led 6W 3000K\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/light24.lv"},{"label":"E-shop","link":"https:\/\/light24.lv\/en\/e-shop\/"},{"label":"Outdoor lighting","link":"https:\/\/light24.lv\/en\/product-category\/outdoor-lighting\/"},{"label":"Outdoor recessed lights","link":"https:\/\/light24.lv\/en\/product-category\/outdoor-lighting\/outdoor-recessed-lights\/"},{"label":"Onelight Trimless Inground Led 6W 3000K","link":"https:\/\/light24.lv\/en\/toode\/outdoor-lighting\/outdoor-recessed-lights\/the-trimless-inground-range-led\/"}],"_links":{"self":[{"href":"https:\/\/light24.lv\/en\/wp-json\/wp\/v2\/product\/361754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/light24.lv\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/light24.lv\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/light24.lv\/en\/wp-json\/wp\/v2\/comments?post=361754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/light24.lv\/en\/wp-json\/wp\/v2\/media\/109422"}],"wp:attachment":[{"href":"https:\/\/light24.lv\/en\/wp-json\/wp\/v2\/media?parent=361754"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/light24.lv\/en\/wp-json\/wp\/v2\/product_brand?post=361754"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/light24.lv\/en\/wp-json\/wp\/v2\/product_cat?post=361754"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/light24.lv\/en\/wp-json\/wp\/v2\/product_tag?post=361754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}